{"id":37435,"date":"2022-04-08T15:57:32","date_gmt":"2022-04-08T13:57:32","guid":{"rendered":"https:\/\/arches-papers.com\/?p=37435"},"modified":"2024-02-05T14:57:47","modified_gmt":"2024-02-05T13:57:47","slug":"exposition-henri-matisse-jazz-le-bon-a-tirer","status":"publish","type":"post","link":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/","title":{"rendered":"Exposition Henri Matisse, <i>Jazz<\/i>, le bon \u00e0 tirer"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab <em>Jazz<\/em> \u00bb, le bon \u00e0 tirer in\u00e9dit des compositions du c\u00e9l\u00e8bre livre publi\u00e9 par T\u00e9riade en 1947. Elle met \u00e0 l&#8217;honneur un ensemble unique de pochoirs et papiers d\u00e9coup\u00e9s uniques de l&#8217;artiste.<\/p>\n<p>Cet ouvrage est le fruit d\u2019une collaboration avec T\u00e9riade. Critique d\u2019art d\u2019origine grecque, il fut \u00e0 partir de 1929 et pratiquement jusqu\u2019\u00e0 sa mort, le confident artistique privil\u00e9gi\u00e9 de Matisse. C\u2019est Katina, la filleule de T\u00e9riade, et son mari Costa qui ont confi\u00e9 \u00e0 la galerie de l\u2019Institut cet ensemble de vingt planches uniques, constituant le bon \u00e0 tirer (B\u00e0T) de <em>Jazz<\/em>. Katina avait re\u00e7u ces planches en cadeau de mariage.<br \/>\nLes B\u00e0T sont les pochoirs ex\u00e9cut\u00e9s d\u2019apr\u00e8s les maquettes originales, sur lesquels Matisse a ajout\u00e9, tant\u00f4t des annotations au crayon, tant\u00f4t des \u00e9l\u00e9ments en papier gouach\u00e9 d\u00e9coup\u00e9 qui recouvrent les formes dont la couleur obtenue au pochoir n\u2019\u00e9tait pas exactement celle qu\u2019il souhaitait. Enfin, l\u2019artiste a sign\u00e9 de ses initiales les ajustements indiqu\u00e9s et annot\u00e9 les \u00e9preuves du traditionnel \u00ab Bon \u00e0 tirer \u00bb ou d\u2019un simple \u00ab B \u00bb.<br \/>\nLes \u0153uvres de la s\u00e9rie <em>Jazz<\/em> ont \u00e9t\u00e9 r\u00e9alis\u00e9es sur papier gouach\u00e9 d\u00e9coup\u00e9 et coll\u00e9 sur papier Velin d\u2019ARCHES\u00ae.<\/p>\n<p><a href=\"https:\/\/arches-papers.com\/fr\/la-gamme-papiers-arches\/papiers-edition-dart-arches\/velin-d-arches-dessin-creme\/\">Velin d&#8217;ARCHES &#8211; Arches Papers (arches-papers.com)<\/a><\/p>\n<h3><em>Jazz<\/em> dans l\u2019\u0153uvre de Matisse<\/h3>\n<p>Cr\u00e9\u00e9 entre 1943 et 1947, l&#8217;ouvrage <em>Jazz<\/em> est une \u0153uvre cl\u00e9 dans l\u2019\u0152uvre d&#8217;Henri Matisse. C\u2019est le laboratoire qui lui permet de passer de la peinture \u00e0 la pratique du papier d\u00e9coup\u00e9, technique d\u00e9velopp\u00e9e dans la derni\u00e8re d\u00e9cennie de sa vie. Elle abrite de nombreux chefs-\u0153uvres, parmi lesquels Le Cow Boy, Le Lanceur de couteaux, Le Toboggan ou encore Icare. <em>Jazz<\/em> est un ensemble de vingt planches en couleurs scand\u00e9es de pages de textes.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;37447&#8243; img_size=&#8221;full&#8221; add_caption=&#8221;yes&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1649403443370{margin-top: 30px !important;margin-bottom: 30px !important;}&#8221;][vc_column_text]C\u2019est avec\u00a0<em>Jazz<\/em> que se met en place la gouache d\u00e9coup\u00e9e qui, \u00e0 partir de 1948, devient le moyen d\u2019expression privil\u00e9gi\u00e9 de Matisse, r\u00e9unissant en une unit\u00e9 le dessin, la couleur, la sculpture.\u00a0 L\u2019artiste ex\u00e9cute les maquettes en gouache d\u00e9coup\u00e9e entre juin 1943 et l\u2019\u00e9t\u00e9 1944. Elles sont, dans le livre, reproduites au pochoir avec exactement les m\u00eames gouaches. Puis, il r\u00e9dige le texte et le calligraphie au roseau et \u00e0 l\u2019encre, sur les pages laiss\u00e9es vides et blanches, dans une \u00e9criture monumentale dessin\u00e9e en 1946.<\/p>\n<p>D\u00e8s le milieu des ann\u00e9es trente, Matisse avait commenc\u00e9 \u00e0 utiliser ponctuellement des aplats de papier d\u00e9coup\u00e9. Mais la guerre, et peut-\u00eatre encore davantage la grave op\u00e9ration chirurgicale subie en 1941, suscitent une nouvelle phase de recherche. Surnomm\u00e9 \u00e0 l\u2019h\u00f4pital \u00ab le ressuscit\u00e9 \u00bb, Matisse se consid\u00e9ra v\u00e9ritablement comme gratifi\u00e9 d\u2019une seconde vie alors qu\u2019il entrait dans la vieillesse. La technique de papiers color\u00e9s \u00e0 la gouache puis d\u00e9coup\u00e9s aux ciseaux, assembl\u00e9s et coll\u00e9s, v\u00e9hiculait plus directement et simplement que jamais une \u00e9motion demeur\u00e9e intacte, la fra\u00eecheur d\u2019une sensation premi\u00e8re. Il est remarquable que cette technique nouvelle ait \u00e9t\u00e9 trouv\u00e9e en d\u00e9pit (ou \u00e0 cause) de l\u2019\u00e2ge et de la ma\u00eetrise. <em>Jazz\u00a0<\/em>ouvrait la voie \u00e0 une technique synth\u00e9tique dans laquelle la couleur \u00e9tait \u00e0 la fois forme, contour, surface, densit\u00e9, profondeur et mouvement.<\/p>\n<p><span style=\"font-size: 24px; font-family: georgia, palatino, serif;\"><em>\u00ab Au lieu de dessiner le contour et d\u2019y installer la couleur \u2013 l\u2019un modifiant l\u2019autre \u2013 je dessine directement dans la couleur qui est d\u2019autant plus mesur\u00e9e qu\u2019elle n\u2019est pas transpos\u00e9e. Cette simplification garantit une pr\u00e9cision dans la r\u00e9union des deux moyens qui ne font plus qu\u2019un \u00bb<\/em><\/span><\/p>\n<p>Henri Matisse 1951.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab Jazz \u00bb, le bon \u00e0 tirer in\u00e9dit des compositions du c\u00e9l\u00e8bre livre publi\u00e9 par T\u00e9riade en 1947. Elle met \u00e0 l&#8217;honneur un ensemble unique de pochoirs et papiers d\u00e9coup\u00e9s uniques de l&#8217;artiste.","protected":false},"author":17,"featured_media":37440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[461],"tags":[],"class_list":["post-37435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Henri Matisse Jazz, l&#039;exposition parisienne - Arches papers<\/title>\n<meta name=\"description\" content=\"La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab Jazz \u00bb, le bon \u00e0 tirer in\u00e9dit...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Henri Matisse Jazz, l&#039;exposition parisienne - Arches papers\" \/>\n<meta property=\"og:description\" content=\"La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab Jazz \u00bb, le bon \u00e0 tirer in\u00e9dit...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/\" \/>\n<meta property=\"og:site_name\" content=\"Arches Papers\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T13:57:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T13:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1072\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eliane\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliane\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/\"},\"author\":{\"name\":\"Eliane\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/a7d908ec620cb78aac5020e0c7868bb6\"},\"headline\":\"Exposition Henri Matisse, Jazz, le bon \u00e0 tirer\",\"datePublished\":\"2022-04-08T13:57:32+00:00\",\"dateModified\":\"2024-02-05T13:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/\"},\"wordCount\":710,\"image\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/\",\"url\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/\",\"name\":\"Henri Matisse Jazz, l'exposition parisienne - Arches papers\",\"isPartOf\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg\",\"datePublished\":\"2022-04-08T13:57:32+00:00\",\"dateModified\":\"2024-02-05T13:57:47+00:00\",\"author\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/a7d908ec620cb78aac5020e0c7868bb6\"},\"description\":\"La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab Jazz \u00bb, le bon \u00e0 tirer in\u00e9dit...\",\"breadcrumb\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage\",\"url\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg\",\"contentUrl\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg\",\"width\":1600,\"height\":1072,\"caption\":\"Henri Matisse exhibition Jazz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/arches-papers.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposition Henri Matisse, Jazz, le bon \u00e0 tirer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#website\",\"url\":\"https:\/\/arches-papers.com\/fr\/\",\"name\":\"Arches Papers\",\"description\":\"Fabricant de papier\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arches-papers.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/a7d908ec620cb78aac5020e0c7868bb6\",\"name\":\"Eliane\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32332ae486056bf40e0ee1b810d0d16a31919fc2e459e2ddfa9fcfc91ffad518?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32332ae486056bf40e0ee1b810d0d16a31919fc2e459e2ddfa9fcfc91ffad518?s=96&d=mm&r=g\",\"caption\":\"Eliane\"},\"url\":\"https:\/\/arches-papers.com\/fr\/author\/eliane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Henri Matisse Jazz, l'exposition parisienne - Arches papers","description":"La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab Jazz \u00bb, le bon \u00e0 tirer in\u00e9dit...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/","og_locale":"fr_FR","og_type":"article","og_title":"Henri Matisse Jazz, l'exposition parisienne - Arches papers","og_description":"La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab Jazz \u00bb, le bon \u00e0 tirer in\u00e9dit...","og_url":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/","og_site_name":"Arches Papers","article_published_time":"2022-04-08T13:57:32+00:00","article_modified_time":"2024-02-05T13:57:47+00:00","og_image":[{"width":1600,"height":1072,"url":"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg","type":"image\/jpeg"}],"author":"Eliane","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Eliane","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#article","isPartOf":{"@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/"},"author":{"name":"Eliane","@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/a7d908ec620cb78aac5020e0c7868bb6"},"headline":"Exposition Henri Matisse, Jazz, le bon \u00e0 tirer","datePublished":"2022-04-08T13:57:32+00:00","dateModified":"2024-02-05T13:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/"},"wordCount":710,"image":{"@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage"},"thumbnailUrl":"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/","url":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/","name":"Henri Matisse Jazz, l'exposition parisienne - Arches papers","isPartOf":{"@id":"https:\/\/arches-papers.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage"},"image":{"@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage"},"thumbnailUrl":"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg","datePublished":"2022-04-08T13:57:32+00:00","dateModified":"2024-02-05T13:57:47+00:00","author":{"@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/a7d908ec620cb78aac5020e0c7868bb6"},"description":"La galerie de l\u2019Institut \u00e0 Paris propose jusqu\u2019au 23 avril 2022 une exposition \u00e9v\u00e8nement : Henri Matisse, \u00ab Jazz \u00bb, le bon \u00e0 tirer in\u00e9dit...","breadcrumb":{"@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#primaryimage","url":"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg","contentUrl":"https:\/\/arches-papers.com\/wp-content\/uploads\/2022\/04\/Matisse-01.jpg","width":1600,"height":1072,"caption":"Henri Matisse exhibition Jazz"},{"@type":"BreadcrumbList","@id":"https:\/\/arches-papers.com\/fr\/exposition-henri-matisse-jazz-le-bon-a-tirer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/arches-papers.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Exposition Henri Matisse, Jazz, le bon \u00e0 tirer"}]},{"@type":"WebSite","@id":"https:\/\/arches-papers.com\/fr\/#website","url":"https:\/\/arches-papers.com\/fr\/","name":"Arches Papers","description":"Fabricant de papier","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arches-papers.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/a7d908ec620cb78aac5020e0c7868bb6","name":"Eliane","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32332ae486056bf40e0ee1b810d0d16a31919fc2e459e2ddfa9fcfc91ffad518?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32332ae486056bf40e0ee1b810d0d16a31919fc2e459e2ddfa9fcfc91ffad518?s=96&d=mm&r=g","caption":"Eliane"},"url":"https:\/\/arches-papers.com\/fr\/author\/eliane\/"}]}},"_links":{"self":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/posts\/37435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/comments?post=37435"}],"version-history":[{"count":0,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/posts\/37435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/media\/37440"}],"wp:attachment":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/media?parent=37435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/categories?post=37435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/tags?post=37435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}