{"id":41172,"date":"2023-05-16T09:17:04","date_gmt":"2023-05-16T07:17:04","guid":{"rendered":"https:\/\/arches-papers.com\/?p=41172"},"modified":"2024-02-02T16:31:25","modified_gmt":"2024-02-02T15:31:25","slug":"11e-fete-de-lestampe","status":"publish","type":"post","link":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/","title":{"rendered":"11e F\u00caTE DE L\u2019ESTAMPE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;41211&#8243; img_size=&#8221;full&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0. En effet, cette ann\u00e9e un \u00e9v\u00e9nement aura \u00e9galement lieu au Canada !<\/p>\n<p>La F\u00eate de l\u2019estampe est ouverte \u00e0 tous les acteurs de l\u2019estampe : artistes plasticiens, graveurs, lithographes, s\u00e9rigraphes, galeristes, mus\u00e9es, imprimeurs de l\u2019estampe, collectionneurs d\u2019estampes, etc. Tous ont \u00e0 c\u0153ur de mettre l\u2019estampe, sous toutes ses formes, en valeur aupr\u00e8s du public.<\/p>\n<p>Une belle occasion pour les amateurs d\u2019art de d\u00e9couvrir une technique ou un artiste dans l\u2019intimit\u00e9 d\u2019un atelier.<\/p>\n<p>Traditionnellement organis\u00e9s autour du 26 mai, les \u00e9v\u00e9nements sont r\u00e9pertori\u00e9s et class\u00e9s par r\u00e9gions offrant \u00e0 chacun la possibilit\u00e9 de cr\u00e9er son propre parcours de d\u00e9couverte.<\/p>\n<p>Une carte interactive disponible sur <a href=\"https:\/\/www.manifestampe.org\" target=\"_blank\" rel=\"noopener noreferrer\">www.manifestampe.org<\/a> enregistre les manifestations au fur et \u00e0 mesure de leur inscription.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>Un \u00e9v\u00e9nement de la 11e F\u00eate de l\u2019estampe mis en lumi\u00e8re :<\/strong>[\/vc_column_text][vc_single_image image=&#8221;41183&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1684143936183{margin-top: 20px !important;margin-bottom: 20px !important;}&#8221;][vc_column_text]Les 26 et 27 mai 2023, \u00e0 l\u2019occasion de la 11\u00e8me \u00e9dition de la F\u00eate de l\u2019Estampe, Christine Vandrisse pr\u00e9sente au sein de son atelier de Lys-Lez-Lannoy (France) des matrices et exemplaires d\u2019estampes :[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_single_image image=&#8221;41197&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14px;\"><em>Matrice et \u00e9preuve FDE 2023 &#8211; \u00a9 Christine Vandrisse<\/em><\/span><\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_single_image image=&#8221;41204&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14px;\"><em>Matrice et \u00e9preuve FDE 2023 &#8211; \u00a9 Christine Vandrisse<\/em><\/span><\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Certains zincs qui font office de matrice sont issus de la d\u00e9construction\/reconstruction de son atelier, ils sont naturellement oxyd\u00e9s sous le ciel du Nord et retravaill\u00e9s, ou non. Par la taille directe ou indirecte Christine Vandrisse cherche \u00e0 faire jaillir l\u2019expression du mat\u00e9riau.<\/p>\n<blockquote><p>\u00ab Mon geste vise \u00e0 provoquer les accidents qui guideront mon chemin futur. L\u2019action m\u00e9canique ou chimique va r\u00e9v\u00e9ler les intentions communes du zinc et de mes mains guid\u00e9es par le cerveau. L\u2019\u00e9criture nait alors de la spontan\u00e9it\u00e9 et de l\u2019inattendu, en perp\u00e9tuelle recherche \u00bb.<\/p><\/blockquote>\n<p>Une vid\u00e9o \u00ab Le Chant de l\u2019Atelier \u00bb r\u00e9alis\u00e9e en 2017 en comm\u00e9moration de la 1\u00e8re guerre mondiale et pr\u00e9sent\u00e9e dans le parcours de l\u2019installation labellis\u00e9e Centenaire du Chemin des Dames, sera diffus\u00e9e en boucle. La longueur et la lenteur de la vid\u00e9o t\u00e9moignent de la lenteur du travail d\u2019\u00e9dition d\u2019un livre enti\u00e8rement r\u00e9alis\u00e9 \u00e0 la main. On y voit essentiellement les mains de l\u2019artiste graveur imprimeur en train de composer le texte, de graver \u00e0 la pointe s\u00e8che, d\u2019encrer, paumer et faire tourner la presse\u2026<\/p>\n<p>L\u2019atelier qui ouvre ses portes pour l\u2019occasion est \u00e9quip\u00e9 pour la typographie de casses essentiellement Police Caravelle Corps 8 \u00e0 36, d\u2019un lingotier, d\u2019une presse \u00e0 tirage d\u2019\u00e9preuve, d\u2019une presse de reliure, acquisitions ou dons aupr\u00e8s d\u2019anciens imprimeurs ou mus\u00e9e et pour la taille douce d\u2019une Presse de Chartreuse 500 n\u00b0620.<\/p>\n<p>C\u2019est dans cette maison que Christine Vandrisse a cr\u00e9\u00e9 les Editions d\u2019Em\u00e9rence en f\u00e9vrier 2011, Em\u00e9rence est le pr\u00e9nom d\u2019une de ses arri\u00e8res arri\u00e8re-grand-m\u00e8re d\u2019origine flamande. Quelques \u00e9ditions de livres d\u2019artiste sont \u00e9galement pr\u00e9sent\u00e9es.<\/p>\n<p><a href=\"https:\/\/leseditionsdemerence.wordpress.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/leseditionsdemerence.wordpress.com<\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/les.editions.d.emerence\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/les.editions.d.emerence<\/a><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/christinevandrisse\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.instagram.com\/christinevandrisse\/<\/a><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/channel\/UChUouDWdZloFdNafTomh6GA\/videos\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.youtube.com\/channel\/UChUouDWdZloFdNafTomh6GA\/videos<\/a>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_single_image image=&#8221;41190&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_empty_space][vc_column_text]<strong>L\u2019\u00e9v\u00e9nement au Canada <\/strong><\/p>\n<p>Le 26 mai, l\u2019atelier-galerie A. Piroir ouvrira ses portes au public Montr\u00e9alais. Une l\u2019occasion exceptionnelle de d\u00e9couvrir l&#8217;estampe actuelle dans son contexte de cr\u00e9ation.<\/p>\n<p>L\u2019atelier pr\u00e9sentera les estampes de Christine Vandrisse r\u00e9alis\u00e9es \u00e0 partir des matrices expos\u00e9es en France. Les expositions sont pr\u00e9sent\u00e9es au c\u00f4t\u00e9 des presses, dans l\u2019atelier, o\u00f9 le public pourra observer les imprimeurs et les artistes \u00e0 l\u2019\u0153uvre. Les amateurs d\u2019art pourront ainsi suivre la cr\u00e9ation d\u2019une estampe du d\u00e9but jusqu\u2019\u00e0 la fin.<\/p>\n<p>Les Piroir, p\u00e8re et fille, sont Imprimeurs en taille-douce depuis 1975, \u00e9diteurs d\u2019estampes et de livres d\u2019artiste ainsi que galeristes en art imprim\u00e9.<\/p>\n<p><a href=\"mailto:info@piroir.com\">info@piroir.com<\/a><\/p>\n<p><a href=\"https:\/\/www.piroir.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.piroir.com\/<\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/agathe.piroi\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/agathe.piroi<\/a><\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]ARCHES\u00ae propose des papiers sp\u00e9cifiquement adapt\u00e9s \u00e0 l\u2019\u00e9dition d\u2019art.<\/p>\n<p><a href=\"https:\/\/arches-papers.com\/fr\/la-gamme-papiers-arches\/papiers-edition-dart-arches\/\">\u00c9dition d&#8217;art &#8211; Arches Papers (arches-papers.com)<\/a><\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0. En effet, cette ann\u00e9e un \u00e9v\u00e9nement aura \u00e9galement lieu au Canada !","protected":false},"author":18,"featured_media":41176,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[461],"tags":[],"class_list":["post-41172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>11\u00e8 F\u00caTE DE L\u2019ESTAMPE organis\u00e9e par Manifestampe<\/title>\n<meta name=\"description\" content=\"Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0 : il y aura \u00e9galement un \u00e9v\u00e9nement au Canada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"11\u00e8 F\u00caTE DE L\u2019ESTAMPE organis\u00e9e par Manifestampe\" \/>\n<meta property=\"og:description\" content=\"Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0 : il y aura \u00e9galement un \u00e9v\u00e9nement au Canada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/\" \/>\n<meta property=\"og:site_name\" content=\"Arches Papers\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T07:17:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T15:31:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"591\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas C\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas C\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/\"},\"author\":{\"name\":\"Nicolas C\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/2a888d9d97b35de19f649e99dd8716fd\"},\"headline\":\"11e F\u00caTE DE L\u2019ESTAMPE\",\"datePublished\":\"2023-05-16T07:17:04+00:00\",\"dateModified\":\"2024-02-02T15:31:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/\"},\"wordCount\":884,\"image\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/\",\"url\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/\",\"name\":\"11\u00e8 F\u00caTE DE L\u2019ESTAMPE organis\u00e9e par Manifestampe\",\"isPartOf\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg\",\"datePublished\":\"2023-05-16T07:17:04+00:00\",\"dateModified\":\"2024-02-02T15:31:25+00:00\",\"author\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/2a888d9d97b35de19f649e99dd8716fd\"},\"description\":\"Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0 : il y aura \u00e9galement un \u00e9v\u00e9nement au Canada.\",\"breadcrumb\":{\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage\",\"url\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg\",\"contentUrl\":\"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg\",\"width\":900,\"height\":591,\"caption\":\"11e F\u00caTE DE L\u2019ESTAMPE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/arches-papers.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"11e F\u00caTE DE L\u2019ESTAMPE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#website\",\"url\":\"https:\/\/arches-papers.com\/fr\/\",\"name\":\"Arches Papers\",\"description\":\"Fabricant de papier\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arches-papers.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/2a888d9d97b35de19f649e99dd8716fd\",\"name\":\"Nicolas C\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32b8ee9d4ceac83e6cfc8e4c5da7abf4a3d553074d8b9a056d2f9479e9cc0b90?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32b8ee9d4ceac83e6cfc8e4c5da7abf4a3d553074d8b9a056d2f9479e9cc0b90?s=96&d=mm&r=g\",\"caption\":\"Nicolas C\"},\"url\":\"https:\/\/arches-papers.com\/fr\/author\/nicolasche-n\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"11\u00e8 F\u00caTE DE L\u2019ESTAMPE organis\u00e9e par Manifestampe","description":"Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0 : il y aura \u00e9galement un \u00e9v\u00e9nement au Canada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/","og_locale":"fr_FR","og_type":"article","og_title":"11\u00e8 F\u00caTE DE L\u2019ESTAMPE organis\u00e9e par Manifestampe","og_description":"Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0 : il y aura \u00e9galement un \u00e9v\u00e9nement au Canada.","og_url":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/","og_site_name":"Arches Papers","article_published_time":"2023-05-16T07:17:04+00:00","article_modified_time":"2024-02-02T15:31:25+00:00","og_image":[{"width":900,"height":591,"url":"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg","type":"image\/jpeg"}],"author":"Nicolas C","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicolas C","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#article","isPartOf":{"@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/"},"author":{"name":"Nicolas C","@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/2a888d9d97b35de19f649e99dd8716fd"},"headline":"11e F\u00caTE DE L\u2019ESTAMPE","datePublished":"2023-05-16T07:17:04+00:00","dateModified":"2024-02-02T15:31:25+00:00","mainEntityOfPage":{"@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/"},"wordCount":884,"image":{"@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage"},"thumbnailUrl":"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/","url":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/","name":"11\u00e8 F\u00caTE DE L\u2019ESTAMPE organis\u00e9e par Manifestampe","isPartOf":{"@id":"https:\/\/arches-papers.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage"},"image":{"@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage"},"thumbnailUrl":"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg","datePublished":"2023-05-16T07:17:04+00:00","dateModified":"2024-02-02T15:31:25+00:00","author":{"@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/2a888d9d97b35de19f649e99dd8716fd"},"description":"Manifestampe organise la 11\u00e8 \u00e9dition de la F\u00eate de l\u2019estampe autour du 26 mai 2023 en France et au-del\u00e0 : il y aura \u00e9galement un \u00e9v\u00e9nement au Canada.","breadcrumb":{"@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#primaryimage","url":"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg","contentUrl":"https:\/\/arches-papers.com\/wp-content\/uploads\/2023\/05\/bandeau-1000.jpg","width":900,"height":591,"caption":"11e F\u00caTE DE L\u2019ESTAMPE"},{"@type":"BreadcrumbList","@id":"https:\/\/arches-papers.com\/fr\/11e-fete-de-lestampe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/arches-papers.com\/fr\/"},{"@type":"ListItem","position":2,"name":"11e F\u00caTE DE L\u2019ESTAMPE"}]},{"@type":"WebSite","@id":"https:\/\/arches-papers.com\/fr\/#website","url":"https:\/\/arches-papers.com\/fr\/","name":"Arches Papers","description":"Fabricant de papier","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arches-papers.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/2a888d9d97b35de19f649e99dd8716fd","name":"Nicolas C","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arches-papers.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32b8ee9d4ceac83e6cfc8e4c5da7abf4a3d553074d8b9a056d2f9479e9cc0b90?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32b8ee9d4ceac83e6cfc8e4c5da7abf4a3d553074d8b9a056d2f9479e9cc0b90?s=96&d=mm&r=g","caption":"Nicolas C"},"url":"https:\/\/arches-papers.com\/fr\/author\/nicolasche-n\/"}]}},"_links":{"self":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/posts\/41172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/comments?post=41172"}],"version-history":[{"count":0,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/posts\/41172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/media\/41176"}],"wp:attachment":[{"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/media?parent=41172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/categories?post=41172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arches-papers.com\/fr\/wp-json\/wp\/v2\/tags?post=41172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}